{"id":536839,"date":"2024-04-23T15:10:49","date_gmt":"2024-04-23T21:10:49","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=536839"},"modified":"2024-04-23T15:10:53","modified_gmt":"2024-04-23T21:10:53","slug":"candidata-del-pan-expone-en-rueda-de-prensa-su-proyecto-de-trabajo","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/candidata-del-pan-expone-en-rueda-de-prensa-su-proyecto-de-trabajo\/","title":{"rendered":"Candidata del PAN expone en rueda de prensa su proyecto de trabajo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">9<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F23%2Fcandidata-del-pan-expone-en-rueda-de-prensa-su-proyecto-de-trabajo%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/candidata-del-pan-expone-en-rueda-de-prensa-su-proyecto-de-trabajo\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Salvador Altamirano\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo<\/strong>.- Posterior al corte de list\u00f3n inaugural de su casa de campa\u00f1a, a las 11:00 horas, la candidata del Partido Acci\u00f3n Nacional (PAN) a la renovaci\u00f3n de ayuntamiento, Micaela Torres Orta, expuso en rueda de prensa su proyecto de trabajo tendiente a implementar si obtiene el triunfo.<br>Acompa\u00f1ada de quien ser\u00e1 su compa\u00f1era de f\u00f3rmula en la suplencia, Rosalinda Hern\u00e1ndez, de su planilla de regidores y pocos militantes expres\u00f3 que, la prioridad en su plan de trabajo ser\u00e1 la obra p\u00fablica, \u201cya que desgraciadamente cuando la pol\u00edtica se corrompe -acus\u00f3-, el que sufre es el pueblo, porque las obras no son de calidad\u201d.<br>Nosotros -agreg\u00f3-, vamos a tener una licitaci\u00f3n y supervisi\u00f3n constantes de las obras emanadas de los tres \u00f3rdenes de gobierno, para que sean exactas y apegadas a derecho, por lo que los beneficiarios de las mismas ser\u00e1n los principales supervisores para que se construyan de calidad.<br>Detall\u00f3 que, en materia de seguridad p\u00fablica al polic\u00eda municipal se le subir\u00e1 un 70 % de su salario, y se les dar\u00e1n c\u00e1tedras de comportamiento y a los locatarios del mercado municipal que es \u2018el ombligo\u2019 de Huejutla se comprometi\u00f3 con un 50 % para remodelar su estructura.<br>Para finalizar, la abanderada blanquiazul coment\u00f3 que su proyecto de trabajo es de beneficio social pleno, entre ello, becas para estudiantes de excelencia y apoyo al sector salud. Ya tengo localizado el lugar en donde se construir\u00e1 el relleno sanitario, ya invit\u00e9 a una planta tratadora de aguas residuales -puntualiz\u00f3-.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Salvador Altamirano\/Zunoticia Huejutla, Hgo.- Posterior al corte de list\u00f3n inaugural de su casa de campa\u00f1a, a las 11:00 horas, la candidata del Partido Acci\u00f3n Nacional (PAN) a la renovaci\u00f3n de ayuntamiento, Micaela Torres Orta, expuso en rueda de prensa su proyecto de trabajo tendiente a implementar si obtiene el triunfo.Acompa\u00f1ada de quien ser\u00e1 su&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/candidata-del-pan-expone-en-rueda-de-prensa-su-proyecto-de-trabajo\/\">Seguir leyendo <span class=\"screen-reader-text\">Candidata del PAN expone en rueda de prensa su proyecto de trabajo<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":536840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-536839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=536839"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536839\/revisions"}],"predecessor-version":[{"id":536841,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536839\/revisions\/536841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/536840"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=536839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=536839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=536839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}