{"id":536842,"date":"2024-04-23T15:22:14","date_gmt":"2024-04-23T21:22:14","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=536842"},"modified":"2024-04-23T15:22:18","modified_gmt":"2024-04-23T21:22:18","slug":"se-realizo-foro-por-la-concientizacion-del-autismo","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/se-realizo-foro-por-la-concientizacion-del-autismo\/","title":{"rendered":"Se realiz\u00f3 foro por la concientizaci\u00f3n del autismo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">18<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F23%2Fse-realizo-foro-por-la-concientizacion-del-autismo%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/se-realizo-foro-por-la-concientizacion-del-autismo\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo<\/strong>.- Con el objetivo de concientizar, capacitar y resolver dudas respecto al autismo, la Secretar\u00eda de Bienestar e Inclusi\u00f3n Social (Sebiso), llev\u00f3 a cabo el \u201cPrimer foro por el d\u00eda mundial de concientizaci\u00f3n del autismo\u201d, en el que participaron decenas de acad\u00e9micos, expertos en la materia y personas que, como familiares, viven de cerca esta condici\u00f3n, de manera cotidiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de la Direcci\u00f3n General de Inclusi\u00f3n para las Personas con Discapacidad, se efectu\u00f3 esta actividad en Pachuca, con la presencia de ponentes que expusieron temas como: \u00bfQu\u00e9 es el autismo? Caracter\u00edsticas y diagn\u00f3stico; Necesidades psicosociales de las personas con autismo y sus familias; El autismo y la neurodivergencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma se realizaron los talleres: Necesidades prioritarias en la atenci\u00f3n educativa de personas con autismo; Plan de intervenci\u00f3n integral y Did\u00e1ctica de la ense\u00f1anza en preescolar y primaria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los mensajes emitidos en este foro, se enfatiz\u00f3 la importancia de la empat\u00eda y comprensi\u00f3n con las personas que tienen esta condici\u00f3n, ya que su manera de percibir el mundo es diferente y es necesario establecer &nbsp; acuerdos, ser flexibles y, de esa manera, abrir canales de comunicaci\u00f3n efectiva con los que se contribuya a su desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, explicaron que el autismo cada vez se detecta en mayor n\u00famero de personas y esto se debe al nivel de informaci\u00f3n que ahora existe, as\u00ed como al crecimiento de la atenci\u00f3n p\u00fablica especializada. De esta manera,&nbsp;en la actualidad es posible hacer una detecci\u00f3n m\u00e1s efectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, familiares de personas con autismo compartieron experiencias y retos que han vivido al afrontar esta condici\u00f3n desde el punto de vista del cuidador, as\u00ed como desde la perspectiva del usuario de servicios p\u00fablicos y privados, haciendo observaciones y sugerencias sobre c\u00f3mo podr\u00edan mejorar estos centros de atenci\u00f3n especializada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento participaron diferentes asociaciones civiles, educativas y dependencias gubernamentales, enfocadas en atender a este sector de la poblaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2024\/04\/Zunoticia-Huejutla-1-208.png\" alt=\"\" class=\"wp-image-536844\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- Con el objetivo de concientizar, capacitar y resolver dudas respecto al autismo, la Secretar\u00eda de Bienestar e Inclusi\u00f3n Social (Sebiso), llev\u00f3 a cabo el \u201cPrimer foro por el d\u00eda mundial de concientizaci\u00f3n del autismo\u201d, en el que participaron decenas de acad\u00e9micos, expertos en la materia y personas que, como&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/23\/se-realizo-foro-por-la-concientizacion-del-autismo\/\">Seguir leyendo <span class=\"screen-reader-text\">Se realiz\u00f3 foro por la concientizaci\u00f3n del autismo<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":536843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-536842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=536842"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536842\/revisions"}],"predecessor-version":[{"id":536845,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/536842\/revisions\/536845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/536843"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=536842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=536842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=536842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}