{"id":537555,"date":"2024-04-27T17:10:44","date_gmt":"2024-04-27T23:10:44","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=537555"},"modified":"2024-04-27T17:10:55","modified_gmt":"2024-04-27T23:10:55","slug":"simey-el-poder-solo-tiene-sentido-al-servicio-de-la-gente","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/27\/simey-el-poder-solo-tiene-sentido-al-servicio-de-la-gente\/","title":{"rendered":"Simey: el poder solo tiene sentido al servicio de la gente"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2024%2F04%2F27%2Fsimey-el-poder-solo-tiene-sentido-al-servicio-de-la-gente%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/27\/simey-el-poder-solo-tiene-sentido-al-servicio-de-la-gente\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tepeji, Hgo.<\/strong> Durante su recorrido en la campa\u00f1a electoral rumbo a las pr\u00f3ximas elecciones del 2 de junio, Simey Olvera Bautista, candidata al Senado por el partido Morena, conmin\u00f3 a los ciudadanos a seguir la construcci\u00f3n del segundo piso de la transformaci\u00f3n en el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el arranque simb\u00f3lico de campa\u00f1a de Alfredo San Rom\u00e1n, candidato a presidente municipal de Huejutla, Simey Olvera manifest\u00f3 su compromiso de seguir construyendo con la gente desde la izquierda e invit\u00f3 a los presentes a respaldarlos en un ejercicio de cinco de cinco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras una visita a la huasteca hidalguense, donde se reuni\u00f3 con la comunidad y escuch\u00f3 las necesidades de la regi\u00f3n, la candidata al Senado continu\u00f3 su recorrido en Tepeji del R\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En compa\u00f1\u00eda de Aldo Meza y Tania Valdez, candidatos a diputado local y alcaldesa, Simey Olvera realiz\u00f3 un recorrido en el centro de Tepeji para conocer las inquietudes de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento en Tula, donde acompa\u00f1\u00f3 al candidato a presidente municipal Cristhian Mart\u00ednez Res\u00e9ndiz tambi\u00e9n fue parte de su campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLes encargo que respalden a Morena para que logremos este tan anhelado y esperado Plan C. Por ello, les dejo el compromiso para la presidencia municipal, porque desde ah\u00ed hasta el Senado y la Presidencia de la Rep\u00fablica vamos a gobernar por el bien del pueblo, porque el poder s\u00f3lo tiene sentido si se pone al servicio de la gente\u201d, extern\u00f3 en el encuentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simey Olvera reiter\u00f3 su compromiso con la transformaci\u00f3n de Hidalgo y para representar los intereses del pueblo, trabajando por un futuro mejor para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Tepeji, Hgo. Durante su recorrido en la campa\u00f1a electoral rumbo a las pr\u00f3ximas elecciones del 2 de junio, Simey Olvera Bautista, candidata al Senado por el partido Morena, conmin\u00f3 a los ciudadanos a seguir la construcci\u00f3n del segundo piso de la transformaci\u00f3n en el estado. En el arranque simb\u00f3lico de campa\u00f1a de Alfredo&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2024\/04\/27\/simey-el-poder-solo-tiene-sentido-al-servicio-de-la-gente\/\">Seguir leyendo <span class=\"screen-reader-text\">Simey: el poder solo tiene sentido al servicio de la gente<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":537556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-537555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/537555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=537555"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/537555\/revisions"}],"predecessor-version":[{"id":537557,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/537555\/revisions\/537557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/537556"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=537555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=537555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=537555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}