{"id":636573,"date":"2026-05-12T17:33:56","date_gmt":"2026-05-12T23:33:56","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=636573"},"modified":"2026-05-12T17:35:10","modified_gmt":"2026-05-12T23:35:10","slug":"reconocen-a-docentes-del-subsistema-tecnologico-por-impulsar-nuevo-modelo-educativo","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/12\/reconocen-a-docentes-del-subsistema-tecnologico-por-impulsar-nuevo-modelo-educativo\/","title":{"rendered":"Reconocen a docentes del subsistema tecnol\u00f3gico por impulsar nuevo modelo educativo"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"float:left\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F05%2F12%2Freconocen-a-docentes-del-subsistema-tecnologico-por-impulsar-nuevo-modelo-educativo%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/12\/reconocen-a-docentes-del-subsistema-tecnologico-por-impulsar-nuevo-modelo-educativo\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Destacaron la labor de 642 docentes de universidades tecnol\u00f3gicas y polit\u00e9cnicas del estado.\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Natividad Castrej\u00f3n destac\u00f3 que Hidalgo ocupa el segundo lugar nacional con mayor n\u00famero de universidades del subsistema tecnol\u00f3gico.<\/li>\n<\/ul>\n\n\n\n<p><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p><strong>Pachuca de Soto, Hgo<\/strong>.- El secretario de Educaci\u00f3n P\u00fablica de Hidalgo, Natividad Castrej\u00f3n Valdez y el subsecretario de Educaci\u00f3n Superior de la SEP, Ricardo Villanueva Lomel\u00ed, entregaron 642 reconocimientos a docentes del subsistema tecnol\u00f3gico por obtener el perfil deseable en la implementaci\u00f3n del Nuevo Modelo Educativo.<\/p>\n\n\n\n<p>Durante el acto, Natividad Castrej\u00f3n destac\u00f3 que este reconocimiento refleja el compromiso, dedicaci\u00f3n y vocaci\u00f3n con la que las y los docentes desempe\u00f1an diariamente su labor educativa en beneficio de las y los estudiantes hidalguenses.<\/p>\n\n\n\n<p>\u201cSu labor, muchas veces discreta y poco visible, es fundamental, pues en ella se construyen las bases firmes sobre las que se proyecta el porvenir de la juventud hidalguense\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Asimismo, reiter\u00f3 el compromiso del gobernador Julio Menchaca Salazar de fortalecer la educaci\u00f3n superior y consolidar instituciones acordes con las necesidades actuales del pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-87.png\" alt=\"\" class=\"wp-image-636578\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-87.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-87-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-87-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<p>El titular de la SEPH inform\u00f3 que Hidalgo ocupa el segundo lugar nacional con mayor n\u00famero de universidades del subsistema tecnol\u00f3gico, al contar con ocho tecnol\u00f3gicas y seis polit\u00e9cnicas.<\/p>\n\n\n\n<p>Adem\u00e1s, destac\u00f3 que Hidalgo avanza como l\u00edder nacional en participaci\u00f3n dentro de las nueve l\u00edneas de trabajo coordinadas por la Direcci\u00f3n General de Universidades Tecnol\u00f3gicas y Polit\u00e9cnicas, como parte de la implementaci\u00f3n del Nuevo Modelo Educativo.<\/p>\n\n\n\n<p>Por su parte, Ricardo Villanueva Lomel\u00ed felicit\u00f3 a las y los docentes reconocidos y destac\u00f3 el compromiso demostrado por Hidalgo en este esfuerzo.<\/p>\n\n\n\n<p>\u201cNo es coincidencia que hoy se reconozca a m\u00e1s de 600 docentes; esto refleja el compromiso y la participaci\u00f3n activa del estado\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>En tanto, la directora general de Universidades Tecnol\u00f3gicas y Polit\u00e9cnicas de la SEP, Marlenne Johvana Mendoza Gonz\u00e1lez, explic\u00f3 que este reconocimiento distingue a docentes que participaron en actividades relacionadas con el desarrollo curricular, elaboraci\u00f3n de materiales educativos, adaptaci\u00f3n de la modalidad mixta y otras acciones que fortalecieron la implementaci\u00f3n del Nuevo Modelo Educativo.<\/p>\n\n\n\n<p>En el evento tambi\u00e9n estuvieron presentes la secretaria t\u00e9cnica de la Subsecretar\u00eda de Educaci\u00f3n Superior, Blanca Inguanzo Arias; el subsecretario de Educaci\u00f3n Media Superior y Superior en Hidalgo, Daniel Fragoso Torres; as\u00ed como rectoras y rectores de instituciones de educaci\u00f3n superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- El secretario de Educaci\u00f3n P\u00fablica de Hidalgo, Natividad Castrej\u00f3n Valdez y el subsecretario de Educaci\u00f3n Superior de la SEP, Ricardo Villanueva Lomel\u00ed, entregaron 642 reconocimientos a docentes del subsistema tecnol\u00f3gico por obtener el perfil deseable en la implementaci\u00f3n del Nuevo Modelo Educativo. Durante el acto, Natividad Castrej\u00f3n destac\u00f3 que&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/12\/reconocen-a-docentes-del-subsistema-tecnologico-por-impulsar-nuevo-modelo-educativo\/\">Seguir leyendo <span class=\"screen-reader-text\">Reconocen a docentes del subsistema tecnol\u00f3gico por impulsar nuevo modelo educativo<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":636574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-636573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/636573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=636573"}],"version-history":[{"count":2,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/636573\/revisions"}],"predecessor-version":[{"id":636579,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/636573\/revisions\/636579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/636574"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=636573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=636573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=636573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}