{"id":638310,"date":"2026-05-29T17:30:30","date_gmt":"2026-05-29T23:30:30","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=638310"},"modified":"2026-05-29T17:30:31","modified_gmt":"2026-05-29T23:30:31","slug":"estudiantes-del-cecyteh-huejutla-realizan-practica-de-atencion-al-cliente-y-ventas-creciendo-juntos","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/29\/estudiantes-del-cecyteh-huejutla-realizan-practica-de-atencion-al-cliente-y-ventas-creciendo-juntos\/","title":{"rendered":"Estudiantes del CECyTEH Huejutla realizan pr\u00e1ctica de Atenci\u00f3n al Cliente y ventas &#8220;Creciendo Juntos&#8221;"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F05%2F29%2Festudiantes-del-cecyteh-huejutla-realizan-practica-de-atencion-al-cliente-y-ventas-creciendo-juntos%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/29\/estudiantes-del-cecyteh-huejutla-realizan-practica-de-atencion-al-cliente-y-ventas-creciendo-juntos\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Gabriela Hern\u00e1ndez\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo<\/strong>.- Durante la ma\u00f1ana del viernes 29 de mayo, alumnos del CECyTEH plantel Huejutla, del 4\u00b0 semestre, de la carrera de Procesos de Gesti\u00f3n Administrativa de los grupos H y G, realizaron una pr\u00e1ctica de Atenci\u00f3n al Cliente y ventas, dirigida a sus mam\u00e1s y pap\u00e1s, denominada &#8220;Creciendo Juntos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad tuvo lugar en el arco techo de la instituci\u00f3n educativa, contando con la presencia de la directora del plantel la Dra. Mayra Orta, padres de familia y docentes responsables de la pr\u00e1ctica.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" data-id=\"638312\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-3-39.png\" alt=\"\" class=\"wp-image-638312\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-3-39.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-3-39-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-3-39-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"638313\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-2-97.png\" alt=\"\" class=\"wp-image-638313\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-2-97.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-2-97-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-2-97-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El evento cont\u00f3 con la degustaci\u00f3n de un rico desayuno, n\u00fameros art\u00edsticos, comida, regalos y rifas, en el cual los alumnos fungieron como chefs, meseros, recepcionistas y conductores, poniendo en pr\u00e1ctica el cierre de ventas, atenci\u00f3n al cliente y la verificaci\u00f3n de su satisfacci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este tipo de pr\u00e1cticas los j\u00f3venes fortalecieron sus competencias disciplinares y desarrollaron habilidades fundamentales para su formaci\u00f3n profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liliana Bautista, estudiante de la carrera, dio a conocer que la pr\u00e1ctica tuvo un mes de organizaci\u00f3n y planeaci\u00f3n, en la cual gracias a la habilidad y responsabilidad de alumnos y docentes, fue posible desarrollar este evento con gran \u00e9xito.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"933\" height=\"524\" data-id=\"638314\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-263.png\" alt=\"\" class=\"wp-image-638314\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-263.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-263-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-1-263-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"933\" height=\"524\" data-id=\"638315\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-396.png\" alt=\"\" class=\"wp-image-638315\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-396.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-396-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-396-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, se cont\u00f3 con la participaci\u00f3n de patrocinadores de empresas locales: Fisioterapeuta PhysioBel, Pasteler\u00eda Pier, Boutique floral &#8220;Blossom&#8221;, Fantastic (regalos y bla bla), Tienda deportiva &#8220;Sport like &#8220;, \u00c1UREA (welness studio), Papa 501, Alevos\u00eda, Rancho MX, Rojas Make Up, SR Rojas, Regalos y detalles &#8220;Sorpr\u00e9ndeme&#8221;, Punto Clam, Boutique No problem y Geraldine, Suplementos Fitness Huejutla, SERTEC, Dra. Mayra Orta Hern\u00e1ndez y Froy Quintana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actividades permiten a las y los estudiantes adquirir experiencia y prepararse para enfrentar con \u00e9xito los retos del \u00e1mbito laboral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Gabriela Hern\u00e1ndez\/Zunoticia Huejutla, Hgo.- Durante la ma\u00f1ana del viernes 29 de mayo, alumnos del CECyTEH plantel Huejutla, del 4\u00b0 semestre, de la carrera de Procesos de Gesti\u00f3n Administrativa de los grupos H y G, realizaron una pr\u00e1ctica de Atenci\u00f3n al Cliente y ventas, dirigida a sus mam\u00e1s y pap\u00e1s, denominada &#8220;Creciendo Juntos&#8221;. La actividad&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/29\/estudiantes-del-cecyteh-huejutla-realizan-practica-de-atencion-al-cliente-y-ventas-creciendo-juntos\/\">Seguir leyendo <span class=\"screen-reader-text\">Estudiantes del CECyTEH Huejutla realizan pr\u00e1ctica de Atenci\u00f3n al Cliente y ventas &#8220;Creciendo Juntos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":638311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-638310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=638310"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638310\/revisions"}],"predecessor-version":[{"id":638316,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638310\/revisions\/638316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/638311"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=638310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=638310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=638310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}