{"id":638363,"date":"2026-05-30T14:20:24","date_gmt":"2026-05-30T20:20:24","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=638363"},"modified":"2026-05-30T14:20:26","modified_gmt":"2026-05-30T20:20:26","slug":"da-continuidad-ihe-al-fortalecimiento-de-la-participacion-escolar","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/30\/da-continuidad-ihe-al-fortalecimiento-de-la-participacion-escolar\/","title":{"rendered":"Da continuidad IHE al fortalecimiento de la participaci\u00f3n escolar"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F05%2F30%2Fda-continuidad-ihe-al-fortalecimiento-de-la-participacion-escolar%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/30\/da-continuidad-ihe-al-fortalecimiento-de-la-participacion-escolar\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Realizaron acciones de seguimiento y conformaci\u00f3n de consejos escolares en distintos municipios del estado.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Redacci\u00f3n\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pachuca de Soto, Hgo<\/strong>.- El Instituto Hidalguense de Educaci\u00f3n (IHE), a trav\u00e9s de la Direcci\u00f3n de Participaci\u00f3n Escolar, realiz\u00f3 acciones de seguimiento y conformaci\u00f3n de Consejos de Participaci\u00f3n Escolar en distintos municipios de la entidad, con el prop\u00f3sito de fortalecer la participaci\u00f3n social en la educaci\u00f3n y consolidar el trabajo colaborativo entre autoridades educativas, familias y comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones forman parte de la pol\u00edtica educativa impulsada por el secretario de Educaci\u00f3n P\u00fablica de Hidalgo, Natividad Castrej\u00f3n Valdez, orientada al fortalecimiento de la participaci\u00f3n social y la corresponsabilidad educativa en las comunidades escolares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de estas actividades, la Direcci\u00f3n General de Fortalecimiento Educativo a trav\u00e9s de la Direcci\u00f3n de Participaci\u00f3n Escolar, dieron seguimiento a los Consejos de Participaci\u00f3n Escolar en el Jard\u00edn de Ni\u00f1os \u201cEmilio Hern\u00e1ndez\u201d y la Primaria \u201cJusto Sierra\u201d, en Santiago de Anaya, con acompa\u00f1amiento para fortalecer la organizaci\u00f3n y participaci\u00f3n de la comunidad educativa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-402.png\" alt=\"\" class=\"wp-image-638365\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-402.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-402-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/05\/Zunoticia-Huejutla-402-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en Tepeji del R\u00edo se realizaron acciones de seguimiento en la Escuela Primaria \u201cMar\u00eda \u00c1ngeles\u201d, con estrategias enfocadas al fortalecimiento de la participaci\u00f3n social en el entorno escolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, se llev\u00f3 a cabo la conformaci\u00f3n de los Consejos Municipales de Participaci\u00f3n Escolar en Tula de Allende y Tizayuca, con espacios de coordinaci\u00f3n y corresponsabilidad entre autoridades educativas, municipales y sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones reflejan el compromiso del IHE con la construcci\u00f3n de entornos educativos m\u00e1s participativos, incluyentes y colaborativos, y fortalecen la participaci\u00f3n social como un eje fundamental para el desarrollo educativo en Hidalgo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Redacci\u00f3n\/Zunoticia Pachuca de Soto, Hgo.- El Instituto Hidalguense de Educaci\u00f3n (IHE), a trav\u00e9s de la Direcci\u00f3n de Participaci\u00f3n Escolar, realiz\u00f3 acciones de seguimiento y conformaci\u00f3n de Consejos de Participaci\u00f3n Escolar en distintos municipios de la entidad, con el prop\u00f3sito de fortalecer la participaci\u00f3n social en la educaci\u00f3n y consolidar el trabajo colaborativo entre autoridades&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/05\/30\/da-continuidad-ihe-al-fortalecimiento-de-la-participacion-escolar\/\">Seguir leyendo <span class=\"screen-reader-text\">Da continuidad IHE al fortalecimiento de la participaci\u00f3n escolar<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":638364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[208],"tags":[214],"class_list":["post-638363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estado","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=638363"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638363\/revisions"}],"predecessor-version":[{"id":638366,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638363\/revisions\/638366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/638364"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=638363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=638363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=638363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}