{"id":638630,"date":"2026-06-02T17:32:58","date_gmt":"2026-06-02T23:32:58","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=638630"},"modified":"2026-06-02T17:33:00","modified_gmt":"2026-06-02T23:33:00","slug":"emite-ine-programacion-de-recorrido-de-modulos-de-atencion-ciudadana-por-sierra-y-huasteca","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/02\/emite-ine-programacion-de-recorrido-de-modulos-de-atencion-ciudadana-por-sierra-y-huasteca\/","title":{"rendered":"Emite INE programaci\u00f3n de recorrido de M\u00f3dulos de Atenci\u00f3n Ciudadana por Sierra y Huasteca"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F06%2F02%2Femite-ine-programacion-de-recorrido-de-modulos-de-atencion-ciudadana-por-sierra-y-huasteca%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/02\/emite-ine-programacion-de-recorrido-de-modulos-de-atencion-ciudadana-por-sierra-y-huasteca\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Enedino Hern\u00e1ndez \/ Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo<\/strong>.- Ezequiel Ramos Islas, jefe de oficina de Seguimiento y An\u00e1lisis del INE en Huejutla de Reyes, confirm\u00f3 el recorrido de los M\u00f3dulos de Atenci\u00f3n Ciudadana por las comunidades y municipios de la Sierra y la Huasteca Hidalguense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que el M\u00f3dulo 130152 estuvo el lunes 1 de junio en Tlachapa, Atlapexco; el martes 2 en Tecacahuaco del mismo municipio; el mi\u00e9rcoles 3 en Xoxolpa, el jueves 4 en Zacayahuatl y el viernes 5 de junio en Chiatitla, estos tres de Yahualica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte el M\u00f3dulo 130153 el lunes 1 de junio estuvo en Tolago, el martes 2 en Xuchitlan, el mi\u00e9rcoles 3 en Xalcuatla, estos de Lolotla; el jueves 4 en Huitepec, Tlanchinol y el viernes 5 de junio en Tentla, Lolotla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confirma que son tres los documentos en original los que deben de presentarse para hacer el tr\u00e1mite de la credencial de elector con fotograf\u00eda y son: acta de nacimiento, identificaci\u00f3n oficial con fotograf\u00eda y comprobante de domicilio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Enedino Hern\u00e1ndez \/ Zunoticia Huejutla, Hgo.- Ezequiel Ramos Islas, jefe de oficina de Seguimiento y An\u00e1lisis del INE en Huejutla de Reyes, confirm\u00f3 el recorrido de los M\u00f3dulos de Atenci\u00f3n Ciudadana por las comunidades y municipios de la Sierra y la Huasteca Hidalguense. Dijo que el M\u00f3dulo 130152 estuvo el lunes 1 de junio&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/02\/emite-ine-programacion-de-recorrido-de-modulos-de-atencion-ciudadana-por-sierra-y-huasteca\/\">Seguir leyendo <span class=\"screen-reader-text\">Emite INE programaci\u00f3n de recorrido de M\u00f3dulos de Atenci\u00f3n Ciudadana por Sierra y Huasteca<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":638631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-638630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=638630"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638630\/revisions"}],"predecessor-version":[{"id":638632,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/638630\/revisions\/638632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/638631"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=638630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=638630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=638630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}