{"id":639051,"date":"2026-06-06T22:11:50","date_gmt":"2026-06-07T04:11:50","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=639051"},"modified":"2026-06-06T22:11:52","modified_gmt":"2026-06-07T04:11:52","slug":"pierde-la-vida-con-proyectil-de-arma-de-fuego-artesanal","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/06\/pierde-la-vida-con-proyectil-de-arma-de-fuego-artesanal\/","title":{"rendered":"Pierde la vida con proyectil de arma de fuego artesanal"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F06%2F06%2Fpierde-la-vida-con-proyectil-de-arma-de-fuego-artesanal%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/06\/pierde-la-vida-con-proyectil-de-arma-de-fuego-artesanal\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<ul class=\"wp-block-list\">\n<li>Presuntamente manipulaba el arma cuando repentinamente se le fue un balazo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Roberto Ram\u00edrez\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atlapexco, Hgo.-<\/strong> Una persona del g\u00e9nero masculino perdi\u00f3 la vida presuntamente al herirse en su cuerpo con un arma de fuego artesanal, sus familiares y conocidos a\u00fan lo trasladaron al Hospital Integral de Atlapexco, pero por la gravedad de la lesi\u00f3n&nbsp;&nbsp; perdi\u00f3 la vida antes de llegar a esa cl\u00ednica, al lugar de los hechos llegaron agentes ministeriales para investigar los hechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presuntamente est\u00e1 persona estaba manipulando un arma de fuego artesanal en la comunidad de Cochiscuatitla y de manera repentina el arma se accion\u00f3 y se lesion\u00f3 a la altura del pecho, sus familiares que escucharon el estruendo de inmediato lo auxiliaron y lo trasladaron al hospital integral de ese municipio, pero al llegar ya no ten\u00eda signos vitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar a ese hospital, arribaron peritos y agentes de la Agencia del Ministerio P\u00fablico de Huejutla, para dar fe de los hechos y ordenar el traslado del cuerpo al Servicio M\u00e9dico Forense para la autopsia correspondiente, asimismo se integr\u00f3 una carpeta de investigaci\u00f3n para indagar los hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Ram\u00edrez\/Zunoticia Atlapexco, Hgo.- Una persona del g\u00e9nero masculino perdi\u00f3 la vida presuntamente al herirse en su cuerpo con un arma de fuego artesanal, sus familiares y conocidos a\u00fan lo trasladaron al Hospital Integral de Atlapexco, pero por la gravedad de la lesi\u00f3n&nbsp;&nbsp; perdi\u00f3 la vida antes de llegar a esa cl\u00ednica, al lugar&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/06\/pierde-la-vida-con-proyectil-de-arma-de-fuego-artesanal\/\">Seguir leyendo <span class=\"screen-reader-text\">Pierde la vida con proyectil de arma de fuego artesanal<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":639052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[178],"tags":[259],"class_list":["post-639051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiaca","tag-policiaca","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=639051"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639051\/revisions"}],"predecessor-version":[{"id":639053,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639051\/revisions\/639053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/639052"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=639051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=639051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=639051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}