{"id":639642,"date":"2026-06-12T17:36:03","date_gmt":"2026-06-12T23:36:03","guid":{"rendered":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/?p=639642"},"modified":"2026-06-12T17:36:04","modified_gmt":"2026-06-12T23:36:04","slug":"destacada-participacion-del-equipo-de-voleibol-femenil-de-la-sec-no-3","status":"publish","type":"post","link":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/12\/destacada-participacion-del-equipo-de-voleibol-femenil-de-la-sec-no-3\/","title":{"rendered":"Destacada participaci\u00f3n del equipo de voleibol femenil de la Sec. No. 3"},"content":{"rendered":"<aside class=\"mashsb-container mashsb-main mashsb-stretched\"><div class=\"mashsb-box\"><div class=\"mashsb-count mash-large\" style=\"&quot;\"><div class=\"counts mashsbcount\">0<\/div><span class=\"mashsb-sharetext\">SHARES<\/span><\/div><div class=\"mashsb-buttons\"><a class=\"mashicon-facebook mash-large mash-center mashsb-noshadow\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.zunoticia.com%2Fnoticias-de-hidalgo%2F2026%2F06%2F12%2Fdestacada-participacion-del-equipo-de-voleibol-femenil-de-la-sec-no-3%2F\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Share<\/span><\/a><a class=\"mashicon-twitter mash-large mash-center mashsb-noshadow\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&amp;url=https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/12\/destacada-participacion-del-equipo-de-voleibol-femenil-de-la-sec-no-3\/\" target=\"_top\" rel=\"nofollow\"><span class=\"icon\"><\/span><span class=\"text\">Tweet<\/span><\/a><div class=\"onoffswitch2 mash-large mashsb-noshadow\" style=\"display:none\"><\/div><\/div>\n            <\/div>\n                <div style=\"clear:both\"><\/div><div class=\"mashsb-toggle-container\"><\/div><\/aside>\n            <!-- Share buttons by mashshare.net - Version: 4.0.47-->\n<p class=\"wp-block-paragraph\"><em>Por Gabriela Hern\u00e1ndez\/Zunoticia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Huejutla, Hgo<\/strong>.- El equipo femenil de voleibol de la Escuela Secundaria General No. 3 &#8220;Carlos Fayad Orozco&#8221;, ubicada en la colonia Parque de poblamiento, logr\u00f3 una destacada participaci\u00f3n en los Juegos Deportivos Nacionales Escolares de la Educaci\u00f3n B\u00e1sica CONADE 2026, celebrados en la ciudad de Guadalajara, Jalisco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con entrega, disciplina y el esp\u00edritu deportivo que las distingue, representaron con orgullo al estado de Hidalgo y al municipio de Huejutla de Reyes, obteniendo el 6to. lugar de participaci\u00f3n, de 30 instituciones educativas que participaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estamos muy orgullosos, muy contentos y emocionados de que nuestra escuela Carlos Fayad Orozco, haya representado a nuestro Estado, en tan importante evento nacional, esperemos que el pr\u00f3ximo ciclo, obtengamos un lugar m\u00e1s alto, seguiremos trabajando arduamente&#8221; expres\u00f3 la directora Graciela Campoy Bautista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, reconoci\u00f3 la labor del profesor de Educaci\u00f3n F\u00edsica, Hebert Said Lara Flores, por su trabajo, compromiso y entrega en la formaci\u00f3n deportiva de las alumnas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"933\" height=\"524\" src=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/06\/Zunoticia-Huejutla-1-122.png\" alt=\"\" class=\"wp-image-639644\" srcset=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/06\/Zunoticia-Huejutla-1-122.png 933w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/06\/Zunoticia-Huejutla-1-122-300x168.png 300w, https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-content\/uploads\/2026\/06\/Zunoticia-Huejutla-1-122-768x431.png 768w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La competencia, organizada por la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP), y la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (CONADE) reuni\u00f3 a deportistas provenientes de escuelas p\u00fablicas y privadas, participaron en 10 disciplinas: ajedrez, atletismo, b\u00e9isbol 5, b\u00e1squetbol 3\u00d73 y 5\u00d75, futbol escolar 5 vs 5, f\u00fatbol bandera, handball, voleibol y b\u00e1dminton, en las ramas femenil, varonil y mixta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de la competencia, los Juegos promueven h\u00e1bitos de vida saludable, fortalecen la convivencia y consolidan al deporte como una herramienta para la formaci\u00f3n integral, el desarrollo de habilidades socioemocionales y la construcci\u00f3n de una cultura de paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la directora dijo que la Secundaria N\u00famero 3, ha participado en diferentes deportes a nivel nacional, as\u00ed como en proyectos acad\u00e9micos, trabajando de manera integral, siendo un referente de la educaci\u00f3n de calidad que ofrece a los j\u00f3venes estudiantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Gabriela Hern\u00e1ndez\/Zunoticia Huejutla, Hgo.- El equipo femenil de voleibol de la Escuela Secundaria General No. 3 &#8220;Carlos Fayad Orozco&#8221;, ubicada en la colonia Parque de poblamiento, logr\u00f3 una destacada participaci\u00f3n en los Juegos Deportivos Nacionales Escolares de la Educaci\u00f3n B\u00e1sica CONADE 2026, celebrados en la ciudad de Guadalajara, Jalisco. Con entrega, disciplina y el&hellip; <a class=\"more-link\" href=\"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/2026\/06\/12\/destacada-participacion-del-equipo-de-voleibol-femenil-de-la-sec-no-3\/\">Seguir leyendo <span class=\"screen-reader-text\">Destacada participaci\u00f3n del equipo de voleibol femenil de la Sec. No. 3<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":639643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_10159540855086992_322828327761733":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[181],"tags":[121],"class_list":["post-639642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huejutla","tag-huejutla","entry"],"_links":{"self":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/comments?post=639642"}],"version-history":[{"count":1,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639642\/revisions"}],"predecessor-version":[{"id":639645,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/posts\/639642\/revisions\/639645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media\/639643"}],"wp:attachment":[{"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/media?parent=639642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/categories?post=639642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zunoticia.com\/noticias-de-hidalgo\/wp-json\/wp\/v2\/tags?post=639642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}